{"id":13259,"date":"2026-02-09T14:52:38","date_gmt":"2026-02-09T14:52:38","guid":{"rendered":"https:\/\/takecapft.com\/?page_id=13259"},"modified":"2026-05-21T22:57:51","modified_gmt":"2026-05-21T22:57:51","slug":"404-error","status":"publish","type":"page","link":"https:\/\/takecapft.com\/pt\/404-error\/","title":{"rendered":"Erro 404"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"13259\" class=\"elementor elementor-13259\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5640327f e-con-full e-flex e-con e-parent\" data-id=\"5640327f\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-6ff933ef e-con-full e-flex e-con e-child\" data-id=\"6ff933ef\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-34112fd7 elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"34112fd7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading="eager" fetchpriority=\"high\" decoding=\"async\" width=\"753\" height=\"93\" src=\"https:\/\/takecapft.com\/wp-content\/uploads\/2025\/11\/LogoTakeCap.svg\" class=\"attachment-full size-full wp-image-9096\" alt=\"Logo TakeCap FT\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f477870 e-con-full elementor-hidden-mobile e-flex e-con e-child\" data-id=\"f477870\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3d4b0b1c eael-simple-menu-hamburger-align-right eael-hamburger--tablet elementor-widget elementor-widget-eael-simple-menu\" data-id=\"3d4b0b1c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"eael-simple-menu.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<style>\n                        @media screen and (max-width: 1024px) {\n                            .eael-hamburger--tablet {\n                                .eael-simple-menu-horizontal,\n                                .eael-simple-menu-vertical {\n                                    display: none;\n                                }\n                            }\n                            .eael-hamburger--tablet {\n                                .eael-simple-menu-container .eael-simple-menu-toggle {\n                                    display: block;\n                                }\n                            }\n                        }\n                        .eael-simple-menu-container.eael-simple-menu--loading > ul {\n                            display: -webkit-box !important;\n                            display: -ms-flexbox !important;\n                            display: flex !important;\n                            list-style: none !important;\n                        }\n                        .eael-simple-menu-container.eael-simple-menu--loading li ul {\n                            visibility: hidden !important;\n                            opacity: 0 !important;\n                        }\n                    <\/style>            <div data-hamburger-icon=\"&lt;svg aria-hidden=&quot;true&quot; class=&quot;e-font-icon-svg e-fas-bars&quot; viewBox=&quot;0 0 448 512&quot; xmlns=&quot;http:\/\/www.w3.org\/2000\/svg&quot;&gt;&lt;path d=&quot;M16 132h416c8.837 0 16-7.163 16-16V76c0-8.837-7.163-16-16-16H16C7.163 60 0 67.163 0 76v40c0 8.837 7.163 16 16 16zm0 160h416c8.837 0 16-7.163 16-16v-40c0-8.837-7.163-16-16-16H16c-8.837 0-16 7.163-16 16v40c0 8.837 7.163 16 16 16zm0 160h416c8.837 0 16-7.163 16-16v-40c0-8.837-7.163-16-16-16H16c-8.837 0-16 7.163-16 16v40c0 8.837 7.163 16 16 16z&quot;&gt;&lt;\/path&gt;&lt;\/svg&gt;\" data-indicator-icon=\"&lt;svg aria-hidden=&quot;true&quot; class=&quot;e-font-icon-svg e-fas-angle-down&quot; viewBox=&quot;0 0 320 512&quot; xmlns=&quot;http:\/\/www.w3.org\/2000\/svg&quot;&gt;&lt;path d=&quot;M143 352.3L7 216.3c-9.4-9.4-9.4-24.6 0-33.9l22.6-22.6c9.4-9.4 24.6-9.4 33.9 0l96.4 96.4 96.4-96.4c9.4-9.4 24.6-9.4 33.9 0l22.6 22.6c9.4 9.4 9.4 24.6 0 33.9l-136 136c-9.2 9.4-24.4 9.4-33.8 0z&quot;&gt;&lt;\/path&gt;&lt;\/svg&gt;\" data-dropdown-indicator-icon=\"&lt;svg class=&quot;e-font-icon-svg e-fas-angle-down&quot; viewBox=&quot;0 0 320 512&quot; xmlns=&quot;http:\/\/www.w3.org\/2000\/svg&quot;&gt;&lt;path d=&quot;M143 352.3L7 216.3c-9.4-9.4-9.4-24.6 0-33.9l22.6-22.6c9.4-9.4 24.6-9.4 33.9 0l96.4 96.4 96.4-96.4c9.4-9.4 24.6-9.4 33.9 0l22.6 22.6c9.4 9.4 9.4 24.6 0 33.9l-136 136c-9.2 9.4-24.4 9.4-33.8 0z&quot;&gt;&lt;\/path&gt;&lt;\/svg&gt;\" class=\"eael-simple-menu-container eael-simple-menu--loading eael-simple-menu-align-center eael-simple-menu--stretch eael-simple-menu-dropdown-align-left preset-2\" data-hamburger-breakpoints=\"{&quot;mobile&quot;:&quot;Dispositivos m\\u00f3veis no modo retrato (&gt; 767px)&quot;,&quot;mobile_extra&quot;:&quot;Dispositivos m\\u00f3veis no modo paisagem (&gt; 880px)&quot;,&quot;tablet&quot;:&quot;Tablet no modo retrato (&gt; 1024px)&quot;,&quot;tablet_extra&quot;:&quot;Tablet no modo paisagem (&gt; 1200px)&quot;,&quot;desktop&quot;:&quot;Desktop (&gt; 2400px)&quot;,&quot;none&quot;:&quot;Nenhum&quot;}\" data-hamburger-device=\"tablet\">\n                <ul id=\"menu-takecapft\" class=\"eael-simple-menu eael-simple-menu-dropdown-animate-to-top eael-simple-menu-indicator eael-simple-menu-horizontal\"><li id=\"menu-item-10730\" class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-10730\"><a href=\"https:\/\/takecapft.com\/pt\/\">In\u00edcio<\/a><\/li>\n<li id=\"menu-item-7421\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-7421\"><a href=\"https:\/\/takecapft.com\/pt\/about-platform\/\">Sobre a plataforma<\/a><\/li>\n<li id=\"menu-item-7413\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-7413\"><a href=\"https:\/\/takecapft.com\/pt\/how-it-works\/\">Como funciona<\/a><\/li>\n<li id=\"menu-item-7998\" class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-has-children menu-item-7998\"><a href=\"#\">Central de ajuda<\/a>\n<ul class=\"sub-menu\">\n\t<li id=\"menu-item-7999\" class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-7999\"><a href=\"https:\/\/intercom.help\/take-capital-for-traders\/en\/\">Perguntas frequentes<\/a><\/li>\n\t<li id=\"menu-item-1943\" class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-1943\"><a href=\"https:\/\/intercom.help\/take-capital-for-traders\/pt-BR\/articles\/10416222-como-posso-entrar-em-contato-com-a-equipe-de-suporte\">Contato<\/a><\/li>\n<\/ul>\n<\/li>\n<li id=\"menu-item-7417\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-7417\"><a href=\"https:\/\/takecapft.com\/pt\/career\/\">Carreiras<\/a><\/li>\n<li id=\"menu-item-16993\" class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-16993\"><a href=\"\/pt\/challenges\/\">Desafios<\/a><\/li>\n<\/ul>                <button class=\"eael-simple-menu-toggle\">\n                    <span class=\"sr-only\">Menu de altern\u00e2ncia de hamb\u00farguer<\/span>\n                    <svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-bars\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M16 132h416c8.837 0 16-7.163 16-16V76c0-8.837-7.163-16-16-16H16C7.163 60 0 67.163 0 76v40c0 8.837 7.163 16 16 16zm0 160h416c8.837 0 16-7.163 16-16v-40c0-8.837-7.163-16-16-16H16c-8.837 0-16 7.163-16 16v40c0 8.837 7.163 16 16 16zm0 160h416c8.837 0 16-7.163 16-16v-40c0-8.837-7.163-16-16-16H16c-8.837 0-16 7.163-16 16v40c0 8.837 7.163 16 16 16z\"><\/path><\/svg>                <\/button>\n            <\/div>\n            \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-502111de e-con-full e-flex e-con e-child\" data-id=\"502111de\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5a9c4b36 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"5a9c4b36\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/takecapft.com\/pt\/#challenges\" id=\"btn-degrade\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"Layer_2\" data-name=\"Layer 2\" viewbox=\"0 0 154 79.08\"><defs><style>      .cls-1 {        fill: #fff;      }    <\/style><\/defs><g id=\"Layer_2-2\" data-name=\"Layer 2\"><g id=\"Layer_1-2\" data-name=\"Layer 1-2\"><g><path class=\"cls-1\" d=\"M55,.07l45.5,79h32l1.01-1.98-28.4-48.62c-.98-1.77-1.53-3.65-.94-5.68,2.84-9.74,49.01-16.76,49.83-20.24l-1.5-2.49H55Z\"><\/path><path class=\"cls-1\" d=\"M2.65.03L0,8.07l12.7,1.81c12.14,3.95,41.54,67.98,45.8,69.2h32.5L45.54,0,2.65.03Z\"><\/path><\/g><\/g><\/g><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Desafios<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5ed51c64 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"5ed51c64\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/dashboard.takecapft.com\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Entrar<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-68abb5a6 elementor-widget elementor-widget-html\" data-id=\"68abb5a6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<style>\n    \/* =========================================\n       1. SEU CSS PERSONALIZADO\n       ========================================= *\/\n    #langSelect {\n        -webkit-appearance: none;\n        -moz-appearance: none;\n        appearance: none;\n        \/* Mantive seu SVG azul exato *\/\n        background-image: url(\"data:image\/svg+xml,%3csvg xmlns='http:\/\/www.w3.org\/2000\/svg' viewBox='0 0 24 24' fill='none' stroke='%231373F6' stroke-width='3' stroke-linecap='round' stroke-linejoin='round'%3e%3cpolyline points='6 9 12 15 18 9'%3e%3c\/polyline%3e%3c\/svg%3e\");\n        background-repeat: no-repeat;\n        background-position: right 0px center;\n        background-size: 16px;\n        background-color: transparent;\n        border: 1px solid transparent;\n        color: #ffffff; \/* Lembre-se: Texto branco precisa de fundo escuro *\/\n        padding: 5px 25px 5px 5px;\n        border-radius: 5px;\n        font-family: 'Sora', sans-serif;\n        font-size: 1.2em;\n        cursor: pointer;\n        outline: none;\n    }\n    \n    #langSelect option {\n        color: #000; \/* Garante que as op\u00e7\u00f5es sejam leg\u00edveis ao abrir a lista (fundo branco padr\u00e3o) *\/\n    }\n\n    #langSelect::-ms-expand { display: none; }\n\n    \/* =========================================\n       2. CORRE\u00c7\u00d5ES DO GOOGLE TRANSLATE\n       ========================================= *\/\n    .goog-te-banner-frame { display: none !important; }\n    body { top: 0px !important; }\n    #google_translate_element { display: none !important; }\n    .goog-tooltip { display: none !important; }\n    .goog-tooltip:hover { display: none !important; }\n    .goog-text-highlight { background-color: transparent !important; border: none !important; box-shadow: none !important; }\n<\/style>\n\n<select id=\"langSelect\">\n    <option value=\"en\">\ud83c\uddfa\ud83c\uddf8 <\/option> <option value=\"pt\">\ud83c\udde7\ud83c\uddf7<\/option>\n    <option value=\"es\">\ud83c\uddea\ud83c\uddf8<\/option>\n<\/select>\n\n<div id=\"google_translate_element\"><\/div>\n\n<script type=\"text\/javascript\">\n    function googleTranslateElementInit() {\n        new google.translate.TranslateElement({\n            pageLanguage: 'en', \/\/ <--- AQUI ESTAVA O ERRO (Agora est\u00e1 'en' para Ingl\u00eas)\n            includedLanguages: 'en,pt,es', \/\/ Limita apenas \u00e0s l\u00ednguas que voc\u00ea quer\n            autoDisplay: false\n        }, 'google_translate_element');\n    }\n<\/script>\n\n<script type=\"text\/javascript\" src=\"\/\/translate.google.com\/translate_a\/element.js?cb=googleTranslateElementInit\"><\/script>\n\n<script type=\"text\/javascript\">\ndocument.addEventListener('DOMContentLoaded', function() {\n    var langSelect = document.getElementById('langSelect');\n    \n    if(langSelect) {\n        langSelect.addEventListener('change', function() {\n            var selectedLanguage = this.value;\n            var googleCombo = document.querySelector('.goog-te-combo');\n            \n            if (googleCombo) {\n                googleCombo.value = selectedLanguage;\n                googleCombo.dispatchEvent(new Event('change'));\n            }\n        });\n    }\n});\n<\/script>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-67f17d08 e-flex e-con-boxed e-con e-parent\" data-id=\"67f17d08\" data-element_type=\"container\" data-e-type=\"container\" id=\"top\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-4aeb2a80 e-con-full e-flex e-con e-child\" data-id=\"4aeb2a80\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-43157559 elementor-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"43157559\" data-element_type=\"widget\" data-e-type=\"widget\" id=\"listapiscante\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-circle\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119 8 8 119 8 256s111 248 248 248 248-111 248-248S393 8 256 8z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Erro 404<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4431dce9 elementor-widget elementor-widget-heading\" data-id=\"4431dce9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\"><span class=\"text-gradient\" style=\"font-weight:600\">Ops.<\/span><br>\nP\u00e1gina n\u00e3o encontrada!<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-430d35f4 elementor-widget elementor-widget-heading\" data-id=\"430d35f4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Sua busca se aventurou al\u00e9m do universo conhecido.<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4163fcdc elementor-align-center elementor-widget elementor-widget-button\" data-id=\"4163fcdc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/takecapft.com\/pt\/\" id=\"btn-degrade\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"Layer_2\" data-name=\"Layer 2\" viewbox=\"0 0 154 79.08\"><defs><style>      .cls-1 {        fill: #fff;      }    <\/style><\/defs><g id=\"Layer_2-2\" data-name=\"Layer 2\"><g id=\"Layer_1-2\" data-name=\"Layer 1-2\"><g><path class=\"cls-1\" d=\"M55,.07l45.5,79h32l1.01-1.98-28.4-48.62c-.98-1.77-1.53-3.65-.94-5.68,2.84-9.74,49.01-16.76,49.83-20.24l-1.5-2.49H55Z\"><\/path><path class=\"cls-1\" d=\"M2.65.03L0,8.07l12.7,1.81c12.14,3.95,41.54,67.98,45.8,69.2h32.5L45.54,0,2.65.03Z\"><\/path><\/g><\/g><\/g><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Voltar para a p\u00e1gina inicial<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-25d65a8 elementor-widget elementor-widget-html\" data-id=\"25d65a8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<style>\n#menutopo{\n     backdrop-filter: blur(20px);\n    -webkit-backdrop-filter: blur(20px);\n    -moz-backdrop-filter: blur(20px);\n    position: fixed;\n    top:0;\n}\n    #btn-degrade{\n    background: linear-gradient(145deg, #1373f6, #083b80, #083b80, #1373f6);\n    background-size: 400% 400%;\n    -webkit-animation: AnimationName 5s ease infinite;\n    -moz-animation: AnimationName 5s ease infinite;\n    animation: AnimationName 5s ease infinite;\n    transition:0.7s;\n}\n\n@-webkit-keyframes AnimationName {\n    0%{background-position:0% 50%}\n    50%{background-position:100% 10%}\n    100%{background-position:0% 50%}\n}\n\n@-moz-keyframes AnimationName {\n    0%{background-position:0% 50%}\n    50%{background-position:100% 10%}\n    100%{background-position:0% 50%}\n}\n\n@keyframes AnimationName {\n    0%{background-position:0% 50%}\n    50%{background-position:100% 10%}\n    100%{background-position:0% 50%}\n}\n\n#btn-degrade:hover {\n    box-shadow:inset 0px 0px 15px 4px #1373f650;\n    cursor:pointer;\n}\n\n<\/style>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-351aedc4 elementor-widget elementor-widget-html\" data-id=\"351aedc4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<style>\n    #listapiscante .elementor-icon-list-icon{\n    animation: sombra1 1s ease 1s infinite, sombra2 1.5s ease infinite;\n    border-radius:100px;\n}\n\n#listapiscante .elementor-icon-list-icon svg{\n    margin:-1px;\n}\n\n#listapiscante .elementor-icon-list-text{\n    margin-left:5px;\n}\n\n@keyframes sombra1 {\n  0% {\n    box-shadow: 0 0 10px rgba(19, 115, 246);\n  }\n  100% {\n    box-shadow: 0 0 10px rgba(19, 115, 246);\n  }\n}\n\n@keyframes sombra2 {\n  0% {\n    box-shadow: 0 0 0px rgba(19, 115, 246);\n  }\n  100% {\n    box-shadow: 0 0 0px 10px rgba(19, 115, 246, 0);\n  }\n}\n\n.text-gradient {\n    background: -webkit-linear-gradient(20deg,#ffffff, #8fbeff);\n     -webkit-background-clip: text;\n-webkit-text-fill-color: transparent;\nanimation: 3s cubic-bezier(0.2, 0.5, 0.9, 0.6) 2s infinite normal none running textodegradex2;\n    background-image: linear-gradient(45deg, #ffffff, #61A3FF, #ffffff, #61A3FF);\n    background-size: 400% 200%;\n    transition: all .8s;\n}\n@keyframes textodegradex2{\n    0% {\n        background-position: 0 0;\n    }\n    100% {\n        background-position: 100% 0;\n    }\n}\n<\/style>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4dbd607d elementor-widget elementor-widget-html\" data-id=\"4dbd607d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<Style>\n    \/*Personalize  o cursor geral do site aqui*\/\n\nhtml{\ncursor:url('https:\/\/tsete.com\/wp-content\/uploads\/2025\/11\/CursorTCFT.svg'), auto !important;\n}\n\n\/*Personalize  o cursor das partes de clique e hover aqui, caso prefira deixar essas como padr\u00e3o do navegador, basta remover essa parte do c\u00f3digo*\/\n\nhtml.click, html.click a, html.click a:hover, a:hover{\ncursor:url('https:\/\/tsete.com\/wp-content\/uploads\/2025\/11\/CursorTCFT.svg'), auto !important;\n}\n\np{\n    margin-bottom:0;\n}\n\nhtml, body{\n    width:100%;\n    overflow-x: hidden;\n}\n\nbody::-webkit-scrollbar {\n    width: 10px;\n}\n \nbody::-webkit-scrollbar-track {\n    background: #040A1C;\n}\n \nbody::-webkit-scrollbar-thumb{\n    background: #1373F6;\n    background-size: 100% 100%;\n    border-radius: 30px;\n}\n\n::selection{\n    background:#1373F6;\n    color:#ffffff;\n}\n\nhtml{\n    scroll-behavior: smooth !important;\n}\n\n<\/Style>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-520f59e6 elementor-widget elementor-widget-html\" data-id=\"520f59e6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<style>\n    #btn-dashboard{\n    outline:1px solid #FFFFFF30;\n    border-radius:10px;\n    cursor:pointer;\n    backdrop-filter: blur(20px);\n    -webkit-backdrop-filter: blur(20px);\n    -moz-backdrop-filter: blur(20px);\n}\n\n\n<\/style>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7c0f3323 e-flex e-con-boxed e-con e-parent\" data-id=\"7c0f3323\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-41f31e71 e-con-full e-flex e-con e-child\" data-id=\"41f31e71\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-704200fc e-con-full e-flex e-con e-child\" data-id=\"704200fc\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7e40acbd elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"7e40acbd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading="eager" fetchpriority=\"high\" decoding=\"async\" width=\"753\" height=\"93\" src=\"https:\/\/takecapft.com\/wp-content\/uploads\/2025\/11\/LogoTakeCap.svg\" class=\"attachment-full size-full wp-image-9096\" alt=\"Logo TakeCap FT\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1b36ad46 elementor-widget elementor-widget-heading\" data-id=\"1b36ad46\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Sua habilidade \u00e9 a vantagem. Nosso capital \u00e9 a alavancagem.<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-49aec348 e-grid-align-left elementor-shape-rounded elementor-grid-0 elementor-widget elementor-widget-social-icons\" data-id=\"49aec348\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"social-icons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-social-icons-wrapper elementor-grid\" role=\"list\">\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-instagram elementor-repeater-item-839295b\" href=\"https:\/\/www.instagram.com\/takecapitalft\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Instagram<\/span>\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-instagram\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M224.1 141c-63.6 0-114.9 51.3-114.9 114.9s51.3 114.9 114.9 114.9S339 319.5 339 255.9 287.7 141 224.1 141zm0 189.6c-41.1 0-74.7-33.5-74.7-74.7s33.5-74.7 74.7-74.7 74.7 33.5 74.7 74.7-33.6 74.7-74.7 74.7zm146.4-194.3c0 14.9-12 26.8-26.8 26.8-14.9 0-26.8-12-26.8-26.8s12-26.8 26.8-26.8 26.8 12 26.8 26.8zm76.1 27.2c-1.7-35.9-9.9-67.7-36.2-93.9-26.2-26.2-58-34.4-93.9-36.2-37-2.1-147.9-2.1-184.9 0-35.8 1.7-67.6 9.9-93.9 36.1s-34.4 58-36.2 93.9c-2.1 37-2.1 147.9 0 184.9 1.7 35.9 9.9 67.7 36.2 93.9s58 34.4 93.9 36.2c37 2.1 147.9 2.1 184.9 0 35.9-1.7 67.7-9.9 93.9-36.2 26.2-26.2 34.4-58 36.2-93.9 2.1-37 2.1-147.8 0-184.8zM398.8 388c-7.8 19.6-22.9 34.7-42.6 42.6-29.5 11.7-99.5 9-132.1 9s-102.7 2.6-132.1-9c-19.6-7.8-34.7-22.9-42.6-42.6-11.7-29.5-9-99.5-9-132.1s-2.6-102.7 9-132.1c7.8-19.6 22.9-34.7 42.6-42.6 29.5-11.7 99.5-9 132.1-9s102.7-2.6 132.1 9c19.6 7.8 34.7 22.9 42.6 42.6 11.7 29.5 9 99.5 9 132.1s2.7 102.7-9 132.1z\"><\/path><\/svg>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-x-twitter elementor-repeater-item-617b9ff\" href=\"https:\/\/x.com\/takecapft\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">X (Twitter)<\/span>\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-x-twitter\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M389.2 48h70.6L305.6 224.2 487 464H345L233.7 318.6 106.5 464H35.8L200.7 275.5 26.8 48H172.4L272.9 180.9 389.2 48zM364.4 421.8h39.1L151.1 88h-42L364.4 421.8z\"><\/path><\/svg>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-youtube elementor-repeater-item-c3331fc\" href=\"https:\/\/www.youtube.com\/@TakeCapFT\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">YouTube<\/span>\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-youtube\" viewbox=\"0 0 576 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M549.655 124.083c-6.281-23.65-24.787-42.276-48.284-48.597C458.781 64 288 64 288 64S117.22 64 74.629 75.486c-23.497 6.322-42.003 24.947-48.284 48.597-11.412 42.867-11.412 132.305-11.412 132.305s0 89.438 11.412 132.305c6.281 23.65 24.787 41.5 48.284 47.821C117.22 448 288 448 288 448s170.78 0 213.371-11.486c23.497-6.321 42.003-24.171 48.284-47.821 11.412-42.867 11.412-132.305 11.412-132.305s0-89.438-11.412-132.305zm-317.51 213.508V175.185l142.739 81.205-142.739 81.201z\"><\/path><\/svg>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7d7a441d elementor-widget elementor-widget-html\" data-id=\"7d7a441d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<script>\nconst elementonote = document.querySelectorAll(\".screen7s\");\nconst posicaoScroll2 = window.innerHeight * 0.5;\n\nfunction fadeScroll() {\n  elementonote.forEach(elemento => {\n    const elementoTop = elemento.getBoundingClientRect().top - posicaoScroll2;\n\n    if (elementoTop < 380) {\n      elemento.classList.add(\"ativo7s\");\n    } else {\n      elemento.classList.remove(\"ativo7s\");\n    }\n  });\n}\n\nwindow.addEventListener(\"scroll\", fadeScroll);\n<\/script>\n<style>\n    .screen7{\npointer-events: none;\nposition: absolute;\nz-index: 5;\n}\n.screen7s{\n     transition: 5s;\n     transform: perspective(100rem) translate3d(0, 0, -5rem) rotateX(-85deg) scale(1, 1);\n    transform-origin: 50% 100%;\n    transform-style: preserve-3d;\n    will-change: transform;\n    position: absolute;\n}\n\n\n.ativo7s{\n     transition: 5s;\n   transform: perspective(100rem) translate3d(0, 0, -5rem) rotateX(0deg) scale(1, 1);\n    transform-origin: 50% 100%;\n    transform-style: preserve-3d;\n    will-change: transform;\n}\n\n\n.screen7ss{\npointer-events: none;\nz-index: 6;\n}\n<\/style>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-121e4016 elementor-widget elementor-widget-html\" data-id=\"121e4016\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<style>\n    #box1white{\n    box-shadow: inset -2px -2px 4px #181a3214, inset 3px 3px 3px #fff, 0.4777151241141837px 0.4777151241141837px 0.20267736224190752px -0.8125px #1414140d, 1.4487036858627107px 1.4487036858627107px 0.6146329201220813px -1.625px #1414140d, 3.829592112890677px 3.829592112890677px 1.62475833132211px -2.4375px #1414140b, 12px 12px 5.091168824543143px -3.25px #14141407;\n    transform: perspective(1000px) rotateX(10deg) rotateY(10deg) scale(0.95);\n}\n#box1white:hover{\n    transform: perspective(1000px) rotateX(0deg) rotateY(0deg) scale(1);\n}\n\n#box2white{\n    box-shadow: inset -2px -2px 4px #181a3214, inset 3px 3px 3px #fff, 0.4777151241141837px 0.4777151241141837px 0.20267736224190752px -0.8125px #1414140d, 1.4487036858627107px 1.4487036858627107px 0.6146329201220813px -1.625px #1414140d, 3.829592112890677px 3.829592112890677px 1.62475833132211px -2.4375px #1414140b, 12px 12px 5.091168824543143px -3.25px #14141407;\n}\n\n#box2white:hover{\n    transform: perspective(1000px) rotateX(-10deg) scale(1.05);\n}\n\n#box3white{\n    box-shadow: inset -2px -2px 4px #181a3214, inset 3px 3px 3px #fff, 0.4777151241141837px 0.4777151241141837px 0.20267736224190752px -0.8125px #1414140d, 1.4487036858627107px 1.4487036858627107px 0.6146329201220813px -1.625px #1414140d, 3.829592112890677px 3.829592112890677px 1.62475833132211px -2.4375px #1414140b, 12px 12px 5.091168824543143px -3.25px #14141407;\n    transform: perspective(1000px) rotateX(10deg) rotateY(-10deg) scale(0.95);\n}\n\n#box3white:hover{\n    transform: perspective(1000px) rotateX(0deg) rotateY(0deg) scale(1);\n}\n<\/style>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-45d10aee elementor-widget elementor-widget-html\" data-id=\"45d10aee\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<script src=\"https:\/\/unpkg.com\/lenis@1.3.1\/dist\/lenis.min.js\"><\/script>\n<script>\nconst lenis = new Lenis({\n  autoRaf: true,\n  duration: 2,\n});\n<\/script>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-19e06c64 elementor-widget elementor-widget-html\" data-id=\"19e06c64\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<script src=\"https:\/\/cdnjs.cloudflare.com\/ajax\/libs\/ScrollMagic\/2.0.8\/ScrollMagic.min.js\"><\/script>\n<script>\nvar controller = new ScrollMagic.Controller();\n\nvar scene = new ScrollMagic.Scene({\n  triggerElement: \".escala\",\n  triggerHook: \"onLeave\",\n  duration: \"170%\"\n})\n.setPin(\".escala\")\n.addTo(controller)\n.on(\"progress\", function(event) {\n  var escalaElement = document.querySelector(\".aumentar\");\n  var progress = event.progress;\n\n  if (progress > 0.15) {\n    escalaElement.classList.add(\"aumentar1\");\n  } else {\n    escalaElement.classList.remove(\"aumentar1\");\n  }\n  if (progress > 0.3) {\n    escalaElement.classList.add(\"aumentar2\");\n  } else {\n    escalaElement.classList.remove(\"aumentar2\");\n  }\n  if (progress > 0.35) {\n    escalaElement.classList.add(\"aumentar3\");\n  } else {\n    escalaElement.classList.remove(\"aumentar3\");\n  }\n  if (progress > 0.45) {\n    escalaElement.classList.add(\"aumentar4\");\n  } else {\n    escalaElement.classList.remove(\"aumentar4\");\n  }\n  if (progress > 0.55) {\n    escalaElement.classList.add(\"aumentar5\");\n  } else {\n    escalaElement.classList.remove(\"aumentar5\");\n  }\n  if (progress > 0.6) {\n    escalaElement.classList.add(\"aumentar6\");\n  } else {\n    escalaElement.classList.remove(\"aumentar6\");\n  }\n  if (progress > 0.65) {\n    escalaElement.classList.add(\"aumentar7\");\n  } else {\n    escalaElement.classList.remove(\"aumentar7\");\n  }\n  if (progress > 0.7) {\n    escalaElement.classList.add(\"aumentar8\");\n  } else {\n    escalaElement.classList.remove(\"aumentar8\");\n  }\n  if (progress > 0.75) {\n    escalaElement.classList.add(\"aumentar9\");\n  } else {\n    escalaElement.classList.remove(\"aumentar9\");\n  }\n\n  var escala2Element = document.querySelector(\".escala2\");\n  var progress = event.progress;\n\n  if (progress > 0.95) {\n    escala2Element.classList.add(\"escala2ativo\");\n  } else {\n    escala2Element.classList.remove(\"escala2ativo\");\n  }\n\n});\n<\/script>\n<style>\n    .escala{\n    transition: none !important;\n    z-index: 50;\n    opacity: 1;\n    overflow: hidden;\n}\n.escala2{\n    transition: 1s;\n    opacity: 1;\n    possition: absolute;\n    z-index: 50;\n}\n.escala2ativo{\n    transition: 1s;\n    opacity: 0;\n    pointer-events: none;\n}\n.aumentar{\n    transition: 1s;\n    transform: scale(1);\n}\n.aumentar1{\n    transition: 1s;\n    transform: scale(4) translatex(0px);\n}\n.aumentar2{\n    transition: 1s;\n    transform: scale(8) translatex(0px);\n}\n.aumentar3{\n    transition: 1s;\n    transform: scale(12) translatex(0px);\n}\n.aumentar4{\n    transition: 1s;\n    transform: scale(30) translatex(0px);\n}\n.aumentar5{\n    transition: 1s;\n    transform: scale(50) translatex(5px);\n}\n.aumentar6{\n    transition: 1s;\n    transform: scale(90) translatex(8px);\n}\n.aumentar7{\n    transition: 1s;\n    transform: scale(150) translatex(10px);\n}\n.aumentar8{\n    transition: 1s;\n    transform: scale(200) translatex(15px);\n}\n.aumentar9{\n    transition: 1s;\n    transform: scale(300) translatex(20px);\n}\n@media(max-width: 767px){\n.aumentar5{\n    transition: 1s;\n    transform: scale(50) translatex(5px);\n}\n.aumentar6{\n    transition: 1s;\n    transform: scale(90) translatex(8px);\n}\n.aumentar7{\n    transition: 1s;\n    transform: scale(150) translatex(10px);\n}\n.aumentar8{\n    transition: 1s;\n    transform: scale(200) translatex(15px);\n}\n.aumentar9{\n    transition: 1s;\n    transform: scale(300) translatex(20px);\n}\n}\n<\/style>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-550b6ac6 elementor-widget elementor-widget-html\" data-id=\"550b6ac6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<style>\n    #fundocupom{\n    position:fixed;\n    bottom:0;\n    }\n<\/style>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a8bcbe elementor-widget elementor-widget-html\" data-id=\"a8bcbe\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<script>\ndocument.addEventListener('DOMContentLoaded', function() {\n    document.querySelector('.copiar').addEventListener('click', function() {\n        var conteudo = document.querySelector('.copiartexto').innerText;\n        var inputTemp = document.createElement('textarea');\n        inputTemp.value = conteudo;\n        document.body.appendChild(inputTemp);\n        inputTemp.select();\n        inputTemp.setSelectionRange(0, 99999);\n        document.execCommand('copy');\n        document.body.removeChild(inputTemp);\n        alert('Texto copiado para a \u00e1rea de transfer\u00eancia!');\n    });\n});\n<\/script>\n<style>\n    .copiar{\n        cursor: pointer;\n    }\n<\/style>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-30ee5a98 copiartexto elementor-widget elementor-widget-heading\" data-id=\"30ee5a98\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">2026<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2cde6d55 e-con-full e-flex e-con e-child\" data-id=\"2cde6d55\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1a85d985 elementor-widget elementor-widget-heading\" data-id=\"1a85d985\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\"><span class=\"text-gradient\">Sobre n\u00f3s<\/span><\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3b5f786a linksrodape elementor-widget elementor-widget-heading\" data-id=\"3b5f786a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/takecapft.com\/pt\/about\/\">Sobre<\/a><br>\n<a href=\"https:\/\/intercom.help\/take-capital-for-traders\/en\/\">Perguntas frequentes<\/a>\n<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-52879fff e-con-full e-flex e-con e-child\" data-id=\"52879fff\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1f6eefbf elementor-widget elementor-widget-heading\" data-id=\"1f6eefbf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\"><span class=\"text-gradient\">Legal<\/span><\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-27468ae6 linksrodape elementor-widget elementor-widget-heading\" data-id=\"27468ae6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/takecapft.com\/pt\/privacy-policy\/\">Pol\u00edtica de Privacidade<\/a><br>\n<a href=\"https:\/\/intercom.help\/take-capital-for-traders\/en\/articles\/10416232-what-is-the-refund-policy\">Pol\u00edtica de Reembolso<\/a><br>\n<a href=\"https:\/\/intercom.help\/take-capital-for-traders\/en\/articles\/10420370-cookie-policy\">Pol\u00edtica de Cookies<\/a><br>\n<a href=\"https:\/\/takecapft.com\/pt\/terms-and-conditions\/\">Termos e Condi\u00e7\u00f5es<\/a><br>\n<a href=\"https:\/\/intercom.help\/take-capital-for-traders\/en\/articles\/10420322-disclaimer\">Aviso Legal<\/a><\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3f11a432 e-con-full e-flex e-con e-child\" data-id=\"3f11a432\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7d44ced0 elementor-widget elementor-widget-heading\" data-id=\"7d44ced0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\"><span class=\"text-gradient\">Contato<\/span><\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3c199450 elementor-widget elementor-widget-heading\" data-id=\"3c199450\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">support@takecapft.com\n<br>\nCharlestown, Nevis<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-54f79b5a e-con-full e-flex e-con e-child\" data-id=\"54f79b5a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6b87387d elementor-widget elementor-widget-heading\" data-id=\"6b87387d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">2026 \u00a9 Copyright - TakeCap Ft.<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2efdd96d elementor-align-center elementor-widget elementor-widget-button\" data-id=\"2efdd96d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#top\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-arrow-up\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M34.9 289.5l-22.2-22.2c-9.4-9.4-9.4-24.6 0-33.9L207 39c9.4-9.4 24.6-9.4 33.9 0l194.3 194.3c9.4 9.4 9.4 24.6 0 33.9L413 289.4c-9.5 9.5-25 9.3-34.3-.4L264 168.6V456c0 13.3-10.7 24-24 24h-32c-13.3 0-24-10.7-24-24V168.6L69.2 289.1c-9.3 9.8-24.8 10-34.3.4z\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Voltar ao topo<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Home About platform How it works Help center FAQ Contact Us Career Menu de altern\u00e2ncia de hamb\u00farguer Challenges Login \ud83c\uddfa\ud83c\uddf8 \ud83c\udde7\ud83c\uddf7\ud83c\uddea\ud83c\uddf8 404 Error Opss. This Page Not Found! your search has ventured beyond the known universe. Back to Home Your skill is the edge. Our capital is the leverage. Instagram X-twitter Youtube 2026 About Us [&hellip;]<\/p>\n","protected":false},"author":15,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_canvas","meta":{"footnotes":""},"class_list":["post-13259","page","type-page","status-publish","hentry"],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/takecapft.com\/pt\/wp-json\/wp\/v2\/pages\/13259","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/takecapft.com\/pt\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/takecapft.com\/pt\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/takecapft.com\/pt\/wp-json\/wp\/v2\/users\/15"}],"replies":[{"embeddable":true,"href":"https:\/\/takecapft.com\/pt\/wp-json\/wp\/v2\/comments?post=13259"}],"version-history":[{"count":1,"href":"https:\/\/takecapft.com\/pt\/wp-json\/wp\/v2\/pages\/13259\/revisions"}],"predecessor-version":[{"id":16605,"href":"https:\/\/takecapft.com\/pt\/wp-json\/wp\/v2\/pages\/13259\/revisions\/16605"}],"wp:attachment":[{"href":"https:\/\/takecapft.com\/pt\/wp-json\/wp\/v2\/media?parent=13259"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}